{"id":4440,"date":"2014-04-19T10:13:16","date_gmt":"2014-04-19T10:13:16","guid":{"rendered":"http:\/\/www.drivelife.it\/news\/?p=4440"},"modified":"2014-04-26T12:24:36","modified_gmt":"2014-04-26T12:24:36","slug":"lalfa-romeo-a-milano-auto-classica","status":"publish","type":"post","link":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/","title":{"rendered":"L&#8217;ALFA ROMEO A MILANO AUTO CLASSICA"},"content":{"rendered":"<div id=\"attachment_4441\" style=\"width: 730px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4441\" class=\"size-large wp-image-4441\" alt=\"Giulietta TI Italia 1961\" src=\"http:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961-960x618.jpg\" width=\"720\" height=\"463\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961-960x618.jpg 960w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961-580x373.jpg 580w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg 1052w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><p id=\"caption-attachment-4441\" class=\"wp-caption-text\">Giulietta TI Italia 1961<\/p><\/div>\n<h1><strong>IN MOSTRA LA STORIA DEL BISCIONE<\/strong><br \/>\n<strong>E LA NUOVISSIMA ALFA 4C<\/strong><\/h1>\n<p>&#8211; di FEDERICO DI LERNIA &#8211; Giunta alla terza edizione, quest&#8217;anno la manifestazione propone un calendario ancora pi\u00f9 ricco di novit\u00e0 quali eventi speciali, nuove aree per i test drive, uno spazio dedicato alla vendita da parte dei privati e numerosi appuntamenti per vivere appieno l&#8217;esperienza dell&#8217;auto classica e sportiva.<\/p>\n<p>All&#8217;evento non poteva certo mancare Alfa Romeo, il marchio secolare che ha scritto alcune delle pagine pi\u00f9 belle dell&#8217;automobilismo mondiale, un patrimonio fatto di vetture e progettisti, corse e motori, stile e innovazione che hanno segnato il progresso tecnologico e le vicende sportive del Novecento.<\/p>\n<p>Per accogliere un pubblico di appassionati ed esperti, Alfa Romeo \u00e8 presente con un&#8217;area espositiva di forte impatto visivo capace di esaltare la pi\u00f9 autentica passione per l&#8217;automobilismo, di ieri e di <a>oggi<\/a>. In particolare, i visitatori possono conoscere da vicino 3 vetture storiche appartenenti al Museo Storico Alfa Romeo: RL Targa Florio (1923), Alfa Romeo 750 Competizione (1955) e Giulietta Spider prototipo America (1955). Sullo stand anche due esemplari appartenenti a clienti privati &#8211; Giulietta Sprint del 1955 e Giulietta Spider &#8220;Bertone&#8221; del 1955 &#8211; che formano tutte insieme la cornice ideale per le vetture di attuale produzione all&#8217;insegna di quel <em>fil rouge<\/em> che lega da oltre un secolo le automobili del Biscione.<\/p>\n<p>Nell&#8217;area espositiva sono presenti l&#8217;affascinante supercar Alfa Romeo 4C &#8211; l&#8217;icona moderna del marchio che esprime l&#8217;essenza della sportivit\u00e0 coniugando uno stile mozzafiato con prestazioni eccellenti &#8211;\u00a0 e l&#8217;inedita MiTo &#8216;Quadrifoglio Verde&#8217; e la nuova Giulietta, i modelli rinnovati che assicurano stile essenziale, motori compatti e potenti, giusto rapporto peso\/potenza e contenuti tecnici &#8220;made in Alfa Romeo&#8221; votati al piacere di guida.<\/p>\n<h2><strong>Gallery modelli storici di Alfa Romeo<\/strong><\/h2>\n<p><strong><em>\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 16%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-4440 gallery-columns-6 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-ti-italia-1961-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-19611-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-19611-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-19611-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-berlina-palermo-1962\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Berlina-Palermo-1962-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Berlina-Palermo-1962-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Berlina-Palermo-1962-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sz-rally-auto-sci-1962\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-SZ-Rally-Auto-Sci-1962-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-SZ-Rally-Auto-Sci-1962-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-SZ-Rally-Auto-Sci-1962-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-spider-lyon-charbonnieres-stuttgart-1962\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Spider-Lyon-Charbonni\u00e8res-Stuttgart-1962-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Spider-Lyon-Charbonni\u00e8res-Stuttgart-1962-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Spider-Lyon-Charbonni\u00e8res-Stuttgart-1962-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sprint-1957\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1957-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1957-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1957-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giuliettasz1960-1962_1024\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSZ1960-1962_1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSZ1960-1962_1024-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSZ1960-1962_1024-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giuliettasprint1954-156_1024\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSprint1954-156_1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSprint1954-156_1024-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSprint1954-156_1024-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giuliettaspider1955-1962_1024\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSpider1955-1962_1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSpider1955-1962_1024-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaSpider1955-1962_1024-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giuliettaberlina1955-1964_1024\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaBerlina1955-1964_1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaBerlina1955-1964_1024-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GiuliettaBerlina1955-1964_1024-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta1-serie1977-1983_1024\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta1-Serie1977-1983_1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta1-Serie1977-1983_1024-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta1-Serie1977-1983_1024-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sz-coda-tronca-1961\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GIULIETTA-SZ-CODA-TRONCA-1961-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GIULIETTA-SZ-CODA-TRONCA-1961-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GIULIETTA-SZ-CODA-TRONCA-1961-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sz-coda-tronca-1960\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GIULIETTA-SZ-CODA-TRONCA-1960-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GIULIETTA-SZ-CODA-TRONCA-1960-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/GIULIETTA-SZ-CODA-TRONCA-1960-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sprint-1954_3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_3-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_3-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sprint-1954_2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_2-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_2-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-sprint-1954_1\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_1-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Sprint-1954_1-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-berlina-1955\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Berlina-1955-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Berlina-1955-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-Berlina-1955-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta-20turbodelta1983-1984_1024\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-20Turbodelta1983-1984_1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-20Turbodelta1983-1984_1024-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-20Turbodelta1983-1984_1024-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/giulietta_0\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta_0-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta_0-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta_0-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/gilietta-spider-1955\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Gilietta-Spider-1955-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Gilietta-Spider-1955-150x150.jpg 150w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Gilietta-Spider-1955-160x160.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n<\/p>\n<p><\/em><\/strong><\/p>\n<p>L&#8217;evento milanese \u00e8 certamente l&#8217;occasione ideale per celebrare i 60 anni di vita del modello Giulietta, come dimostra anche lo spazio allestito all&#8217;esterno di &#8216;Milano AutoClassica&#8217; per accogliere i 50 esemplari privati che saranno visibili per tutta la durata della Fiera, un vero e proprio museo &#8216;a cielo aperto&#8217; per raccontare la lunga storia di una leggenda.<\/p>\n<p>Era il 1954 quando, sulla scia del successo della 1900, l&#8217;Alfa Romeo presenta al Salone di Torino la Giulietta Sprint, un agile coup\u00e9 dalle dimensioni compatte e con prestazioni superiori che segna l&#8217;ingresso della Casa del Biscione nella categoria delle &#8220;piccole&#8221; con propulsori inferiori ai 1.500 centimetri cubici di cilindrata.<\/p>\n<p>L&#8217;anno successivo \u00e8 la volta della versione berlina, una vettura che anche in questa configurazione non rinuncia alle prestazioni e alla dinamica di guida di alto livello: si consolida la tradizione Alfa Romeo delle &#8220;berline sportive&#8221;, iniziata con la &#8220;1900&#8221;, celebre per essere definita &#8220;la berlina da famiglia che vince le corse&#8221;. Nelle mani dei campioni la Giulietta taglia i traguardi pi\u00f9 ambiti mentre, come sintetizza bene uno slogan del tempo, &#8220;la guida anche la mamma&#8221;. Si apre cos\u00ec un&#8217;epoca e Alfa Romeo \u00e8 precursore nel rendere concreto &#8220;il piacere della guida sportiva alla portata di tutti&#8221;.<\/p>\n<p>Nell&#8217;ottobre dello stesso anno \u00e8 la volta della Giulietta Spider, &#8220;la signorina&#8221; come \u00e8 affettuosamente chiamata dallo stesso Giovanni Battista &#8220;Pinin&#8221; Farina che disegna le sue linee filanti conferendole cos\u00ec una forte personalit\u00e0. Allestita sul pianale della Sprint, ma con passo ridotto, la Giulietta Spider riscuote un successo internazionale. Negli Stati Uniti \u00e8 accolta con entusiasmo e la stampa specializzata la definisce: &#8220;una splendida continuit\u00e0 di quella tradizione italiana che per il suo buongusto fa distinguere un&#8217;Alfa Romeo a colpo d&#8217;occhio fra mille altre&#8221;.<\/p>\n<p>A Milano \u00e8 in mostra proprio la Giulietta Spider prototipo America (1955), una tra le vetture pi\u00f9 belle mai realizzate e un simbolo degli anni Cinquanta, che vanta le stesse prestazioni della Sprint e lo stesso livello tecnico d&#8217;eccellenza tanto da far sembrare subito obsolete le spider della concorrenza. Anche la versione &#8220;veloce&#8221; della spider raggiunge i 180 km\/h, velocit\u00e0 elevatissima per una scoperta compatta degli anni Cinquanta.<\/p>\n<p>Accanto alle Giulietta storiche \u00e8 in mostra un esemplare di Alfa Romeo 750 Competizione (1955), una\u00a0 &#8220;barchetta&#8221; da competizione che venne realizzata nel 1955 per un&#8217;eventuale partecipazione alle gare nella categoria Sport, classe 1,5 litri. Il motore della vettura \u00e8 quello della Giulietta, portato a 1488 cc, per una potenza di 145 cv, che spinge questa spider da corsa a 220 km\/h, grazie anche al peso, in ordine di marcia, pari a 670 kg. Il design della carrozzeria \u00e8 a cura di Boano, si discosta nettamente dallo stile delle altre Alfa Romeo contemporanee. La vettura \u00e8 rimasto allo stadio di prototipo-laboratorio: nel 1955 al Portello dovevano concentrarsi sul consolidamento produttivo della &#8220;Giulietta&#8221;.<\/p>\n<p>Completa la compagine storica del Biscione alla rassegna milanese una preziosa Alfa Romeo RL Targa Florio (1923) che, da una parte, ricorda la prima vittoria di Alfa Romeo in occasione della leggendaria Targa Florio in Sicilia e, dall&#8217;altra, segna la nascita del &#8216;Quadrifoglio Verde&#8217; quale simbolo indissolubilmente legato ai successi sportivi di Alfa Romeo. Infatti, sul cofano dell&#8217;auto condotta alla vittoria da Ugo Sivocci venne dipinto per scaramanzia un quadrifoglio contro il numero di gara 13 che gli era stato assegnato. La vettura del Museo ha il motore originale usato in gara nel &#8217;23: un 6 cilindri in linea di 3154 cc da 95 cavalli che spinge la vettura a 160 km\/h di velocit\u00e0 massima.<\/p>\n<p><span style=\"line-height: 1.5em;\">Altre protagoniste dell&#8217;area espositiva tre vetture di attuale produzione: la supercar Alfa Romeo 4C, la nuova versione &#8216;Quadrifoglio Verde&#8217; di MiTo e la rinnovata Giulietta che quest&#8217;anno celebra i 60 anni di vita del modello-icona degli anni Cinquanta.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IN MOSTRA LA STORIA DEL BISCIONE E LA NUOVISSIMA ALFA 4C &#8211; di FEDERICO DI LERNIA &#8211; Giunta alla terza edizione, quest&#8217;anno la manifestazione propone un calendario ancora pi\u00f9 ricco di novit\u00e0 quali eventi speciali, nuove aree per i test drive, uno spazio dedicato alla vendita da parte dei privati e numerosi appuntamenti per vivere appieno l&#8217;esperienza dell&#8217;auto classica e sportiva. All&#8217;evento non poteva certo mancare Alfa Romeo, il marchio secolare che ha scritto alcune delle pagine pi\u00f9 belle dell&#8217;automobilismo mondiale, un patrimonio fatto di vetture e progettisti, corse e motori, stile e innovazione che hanno segnato il progresso tecnologico e le&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":4441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[94,39],"tags":[352,350],"class_list":["post-4440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alfa-romeo","category-automotive","tag-alfaromeo","tag-milano-auto-classica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ALFA ROMEO A MILANO AUTO CLASSICA - #lucalife<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ALFA ROMEO A MILANO AUTO CLASSICA - #lucalife\" \/>\n<meta property=\"og:description\" content=\"IN MOSTRA LA STORIA DEL BISCIONE E LA NUOVISSIMA ALFA 4C &#8211; di FEDERICO DI LERNIA &#8211; Giunta alla terza edizione, quest&#8217;anno la manifestazione propone un calendario ancora pi\u00f9 ricco di novit\u00e0 quali eventi speciali, nuove aree per i test drive, uno spazio dedicato alla vendita da parte dei privati e numerosi appuntamenti per vivere appieno l&#8217;esperienza dell&#8217;auto classica e sportiva. All&#8217;evento non poteva certo mancare Alfa Romeo, il marchio secolare che ha scritto alcune delle pagine pi\u00f9 belle dell&#8217;automobilismo mondiale, un patrimonio fatto di vetture e progettisti, corse e motori, stile e innovazione che hanno segnato il progresso tecnologico e le&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/\" \/>\n<meta property=\"og:site_name\" content=\"#lucalife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Drivelife\/467833073239720\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-19T10:13:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-26T12:24:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1052\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tweetdrivelife\" \/>\n<meta name=\"twitter:site\" content=\"@tweetdrivelife\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#\\\/schema\\\/person\\\/b6c194c3423ff451be4914f5fd9c2188\"},\"headline\":\"L&#8217;ALFA ROMEO A MILANO AUTO CLASSICA\",\"datePublished\":\"2014-04-19T10:13:16+00:00\",\"dateModified\":\"2014-04-26T12:24:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/\"},\"wordCount\":919,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Giulietta-TI-Italia-1961.jpg\",\"keywords\":[\"alfaromeo\",\"MILANO AUTO CLASSICA\"],\"articleSection\":[\"ALFA ROMEO\",\"AUTOMOTIVE\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/\",\"name\":\"L'ALFA ROMEO A MILANO AUTO CLASSICA - #lucalife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Giulietta-TI-Italia-1961.jpg\",\"datePublished\":\"2014-04-19T10:13:16+00:00\",\"dateModified\":\"2014-04-26T12:24:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#\\\/schema\\\/person\\\/b6c194c3423ff451be4914f5fd9c2188\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Giulietta-TI-Italia-1961.jpg\",\"contentUrl\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Giulietta-TI-Italia-1961.jpg\",\"width\":1052,\"height\":678,\"caption\":\"Giulietta TI Italia 1961\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/19\\\/lalfa-romeo-a-milano-auto-classica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;ALFA ROMEO A MILANO AUTO CLASSICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/\",\"name\":\"#lucalife\",\"description\":\"DRIVELIFE le mie automobili\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#\\\/schema\\\/person\\\/b6c194c3423ff451be4914f5fd9c2188\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d186f6b07ba8a94441344759f0e13bf1909b6ceaa171df0425551b4590fd558?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d186f6b07ba8a94441344759f0e13bf1909b6ceaa171df0425551b4590fd558?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d186f6b07ba8a94441344759f0e13bf1909b6ceaa171df0425551b4590fd558?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ALFA ROMEO A MILANO AUTO CLASSICA - #lucalife","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/","og_locale":"en_US","og_type":"article","og_title":"L'ALFA ROMEO A MILANO AUTO CLASSICA - #lucalife","og_description":"IN MOSTRA LA STORIA DEL BISCIONE E LA NUOVISSIMA ALFA 4C &#8211; di FEDERICO DI LERNIA &#8211; Giunta alla terza edizione, quest&#8217;anno la manifestazione propone un calendario ancora pi\u00f9 ricco di novit\u00e0 quali eventi speciali, nuove aree per i test drive, uno spazio dedicato alla vendita da parte dei privati e numerosi appuntamenti per vivere appieno l&#8217;esperienza dell&#8217;auto classica e sportiva. All&#8217;evento non poteva certo mancare Alfa Romeo, il marchio secolare che ha scritto alcune delle pagine pi\u00f9 belle dell&#8217;automobilismo mondiale, un patrimonio fatto di vetture e progettisti, corse e motori, stile e innovazione che hanno segnato il progresso tecnologico e le&#46;&#46;&#46;","og_url":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/","og_site_name":"#lucalife","article_publisher":"https:\/\/www.facebook.com\/pages\/Drivelife\/467833073239720","article_published_time":"2014-04-19T10:13:16+00:00","article_modified_time":"2014-04-26T12:24:36+00:00","og_image":[{"width":1052,"height":678,"url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@tweetdrivelife","twitter_site":"@tweetdrivelife","twitter_misc":{"Written by":"Redazione","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#article","isPartOf":{"@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.drivelife.it\/news\/#\/schema\/person\/b6c194c3423ff451be4914f5fd9c2188"},"headline":"L&#8217;ALFA ROMEO A MILANO AUTO CLASSICA","datePublished":"2014-04-19T10:13:16+00:00","dateModified":"2014-04-26T12:24:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/"},"wordCount":919,"commentCount":0,"image":{"@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg","keywords":["alfaromeo","MILANO AUTO CLASSICA"],"articleSection":["ALFA ROMEO","AUTOMOTIVE"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/","url":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/","name":"L'ALFA ROMEO A MILANO AUTO CLASSICA - #lucalife","isPartOf":{"@id":"https:\/\/www.drivelife.it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#primaryimage"},"image":{"@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg","datePublished":"2014-04-19T10:13:16+00:00","dateModified":"2014-04-26T12:24:36+00:00","author":{"@id":"https:\/\/www.drivelife.it\/news\/#\/schema\/person\/b6c194c3423ff451be4914f5fd9c2188"},"breadcrumb":{"@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#primaryimage","url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg","contentUrl":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/Giulietta-TI-Italia-1961.jpg","width":1052,"height":678,"caption":"Giulietta TI Italia 1961"},{"@type":"BreadcrumbList","@id":"https:\/\/www.drivelife.it\/news\/2014\/04\/19\/lalfa-romeo-a-milano-auto-classica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.drivelife.it\/news\/"},{"@type":"ListItem","position":2,"name":"L&#8217;ALFA ROMEO A MILANO AUTO CLASSICA"}]},{"@type":"WebSite","@id":"https:\/\/www.drivelife.it\/news\/#website","url":"https:\/\/www.drivelife.it\/news\/","name":"#lucalife","description":"DRIVELIFE le mie automobili","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.drivelife.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.drivelife.it\/news\/#\/schema\/person\/b6c194c3423ff451be4914f5fd9c2188","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8d186f6b07ba8a94441344759f0e13bf1909b6ceaa171df0425551b4590fd558?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d186f6b07ba8a94441344759f0e13bf1909b6ceaa171df0425551b4590fd558?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d186f6b07ba8a94441344759f0e13bf1909b6ceaa171df0425551b4590fd558?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.drivelife.it\/news\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/posts\/4440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/comments?post=4440"}],"version-history":[{"count":6,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/posts\/4440\/revisions"}],"predecessor-version":[{"id":4466,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/posts\/4440\/revisions\/4466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/media\/4441"}],"wp:attachment":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/media?parent=4440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/categories?post=4440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/tags?post=4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}