{"id":4430,"date":"2014-04-26T09:56:21","date_gmt":"2014-04-26T09:56:21","guid":{"rendered":"http:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg"},"modified":"2014-04-26T09:56:21","modified_gmt":"2014-04-26T09:56:21","slug":"131111_ab_595-anniv_08","status":"inherit","type":"attachment","link":"https:\/\/www.drivelife.it\/news\/2014\/04\/18\/lo-scorpione-a-milano-auto-classica\/131111_ab_595-anniv_08\/","title":{"rendered":"131111_AB_595-anniv_08"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-4430","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>131111_AB_595-anniv_08 - #lucalife<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"131111_AB_595-anniv_08 - #lucalife\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg\" \/>\n<meta property=\"og:site_name\" content=\"#lucalife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Drivelife\/467833073239720\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1680\" \/>\n\t<meta property=\"og:image:height\" content=\"1120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tweetdrivelife\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/131111_AB_595-anniv_08.jpg\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/131111_AB_595-anniv_08.jpg\",\"name\":\"131111_AB_595-anniv_08 - #lucalife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#website\"},\"datePublished\":\"2014-04-26T09:56:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/131111_AB_595-anniv_08.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/131111_AB_595-anniv_08.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/131111_AB_595-anniv_08.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LO SCORPIONE A MILANO AUTO CLASSICA\",\"item\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2014\\\/04\\\/18\\\/lo-scorpione-a-milano-auto-classica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"131111_AB_595-anniv_08\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/\",\"name\":\"#lucalife\",\"description\":\"DRIVELIFE le mie automobili\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"131111_AB_595-anniv_08 - #lucalife","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg","og_locale":"en_US","og_type":"article","og_title":"131111_AB_595-anniv_08 - #lucalife","og_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg","og_site_name":"#lucalife","article_publisher":"https:\/\/www.facebook.com\/pages\/Drivelife\/467833073239720","og_image":[{"width":1680,"height":1120,"url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@tweetdrivelife","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg","url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg","name":"131111_AB_595-anniv_08 - #lucalife","isPartOf":{"@id":"https:\/\/www.drivelife.it\/news\/#website"},"datePublished":"2014-04-26T09:56:21+00:00","breadcrumb":{"@id":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.drivelife.it\/news\/"},{"@type":"ListItem","position":2,"name":"LO SCORPIONE A MILANO AUTO CLASSICA","item":"https:\/\/www.drivelife.it\/news\/2014\/04\/18\/lo-scorpione-a-milano-auto-classica\/"},{"@type":"ListItem","position":3,"name":"131111_AB_595-anniv_08"}]},{"@type":"WebSite","@id":"https:\/\/www.drivelife.it\/news\/#website","url":"https:\/\/www.drivelife.it\/news\/","name":"#lucalife","description":"DRIVELIFE le mie automobili","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.drivelife.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"386\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-580x386.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-580x386.jpg 580w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-960x640.jpg 960w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg 1680w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1680,"height":1120,"file":"2014\/04\/131111_AB_595-anniv_08.jpg","sizes":{"thumbnail":{"file":"131111_AB_595-anniv_08-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-150x150.jpg"},"medium":{"file":"131111_AB_595-anniv_08-580x386.jpg","width":580,"height":386,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-580x386.jpg"},"large":{"file":"131111_AB_595-anniv_08-960x640.jpg","width":960,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-960x640.jpg"},"thumb-small":{"file":"131111_AB_595-anniv_08-160x160.jpg","width":160,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-160x160.jpg"},"thumb-medium":{"file":"131111_AB_595-anniv_08-520x245.jpg","width":520,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-520x245.jpg"},"thumb-large":{"file":"131111_AB_595-anniv_08-720x340.jpg","width":720,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08-720x340.jpg"},"full":{"file":"131111_AB_595-anniv_08.jpg","width":1680,"height":1120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg"}},"image_meta":{"aperture":14,"credit":"ALBERTO ALQUATI","camera":"Canon EOS-1D X","caption":"","created_timestamp":1384165150,"copyright":"","focal_length":"300","iso":"125","shutter_speed":"0.005","title":""}},"post":4426,"source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2014\/04\/131111_AB_595-anniv_08.jpg","_links":{"self":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/media\/4430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/comments?post=4430"}]}}