{"id":17243,"date":"2017-07-10T21:00:14","date_gmt":"2017-07-10T21:00:14","guid":{"rendered":"http:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg"},"modified":"2017-07-10T21:00:14","modified_gmt":"2017-07-10T21:00:14","slug":"peugeot_308sw_0905styp_006","status":"inherit","type":"attachment","link":"https:\/\/www.drivelife.it\/news\/2017\/07\/12\/nuova-peugeot-308-2\/peugeot_308sw_0905styp_006\/","title":{"rendered":"PEUGEOT_308SW_0905STYP_006"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-17243","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PEUGEOT_308SW_0905STYP_006 - #lucalife<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEUGEOT_308SW_0905STYP_006 - #lucalife\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg\" \/>\n<meta property=\"og:site_name\" content=\"#lucalife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Drivelife\/467833073239720\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tweetdrivelife\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/PEUGEOT_308SW_0905STYP_006.jpg\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/PEUGEOT_308SW_0905STYP_006.jpg\",\"name\":\"PEUGEOT_308SW_0905STYP_006 - #lucalife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#website\"},\"datePublished\":\"2017-07-10T21:00:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/PEUGEOT_308SW_0905STYP_006.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/PEUGEOT_308SW_0905STYP_006.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/PEUGEOT_308SW_0905STYP_006.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUOVA PEUGEOT 308\",\"item\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/2017\\\/07\\\/12\\\/nuova-peugeot-308-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PEUGEOT_308SW_0905STYP_006\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/\",\"name\":\"#lucalife\",\"description\":\"DRIVELIFE le mie automobili\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.drivelife.it\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEUGEOT_308SW_0905STYP_006 - #lucalife","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","og_locale":"en_US","og_type":"article","og_title":"PEUGEOT_308SW_0905STYP_006 - #lucalife","og_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","og_site_name":"#lucalife","article_publisher":"https:\/\/www.facebook.com\/pages\/Drivelife\/467833073239720","og_image":[{"width":2560,"height":1706,"url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@tweetdrivelife","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","name":"PEUGEOT_308SW_0905STYP_006 - #lucalife","isPartOf":{"@id":"https:\/\/www.drivelife.it\/news\/#website"},"datePublished":"2017-07-10T21:00:14+00:00","breadcrumb":{"@id":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.drivelife.it\/news\/"},{"@type":"ListItem","position":2,"name":"NUOVA PEUGEOT 308","item":"https:\/\/www.drivelife.it\/news\/2017\/07\/12\/nuova-peugeot-308-2\/"},{"@type":"ListItem","position":3,"name":"PEUGEOT_308SW_0905STYP_006"}]},{"@type":"WebSite","@id":"https:\/\/www.drivelife.it\/news\/#website","url":"https:\/\/www.drivelife.it\/news\/","name":"#lucalife","description":"DRIVELIFE le mie automobili","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.drivelife.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"413\" src=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-620x413.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-620x413.jpg 620w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-768x512.jpg 768w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-1000x666.jpg 1000w, https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-300x200.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1706,"file":"2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","sizes":{"thumbnail":{"file":"PEUGEOT_308SW_0905STYP_006-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-150x150.jpg"},"medium":{"file":"PEUGEOT_308SW_0905STYP_006-620x413.jpg","width":620,"height":413,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-620x413.jpg"},"medium_large":{"file":"PEUGEOT_308SW_0905STYP_006-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-768x512.jpg"},"large":{"file":"PEUGEOT_308SW_0905STYP_006-1000x666.jpg","width":1000,"height":666,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-1000x666.jpg"},"shareaholic-thumbnail":{"file":"PEUGEOT_308SW_0905STYP_006-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-300x200.jpg"},"thumb-small":{"file":"PEUGEOT_308SW_0905STYP_006-160x160.jpg","width":160,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-160x160.jpg"},"thumb-standard":{"file":"PEUGEOT_308SW_0905STYP_006-320x320.jpg","width":320,"height":320,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-320x320.jpg"},"thumb-medium":{"file":"PEUGEOT_308SW_0905STYP_006-520x245.jpg","width":520,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-520x245.jpg"},"thumb-large":{"file":"PEUGEOT_308SW_0905STYP_006-720x340.jpg","width":720,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006-720x340.jpg"},"full":{"file":"PEUGEOT_308SW_0905STYP_006.jpg","width":2560,"height":1706,"mime_type":"image\/jpeg","source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1481230076","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":17235,"source_url":"https:\/\/www.drivelife.it\/news\/wp-content\/uploads\/2017\/07\/PEUGEOT_308SW_0905STYP_006.jpg","_links":{"self":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/media\/17243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drivelife.it\/news\/wp-json\/wp\/v2\/comments?post=17243"}]}}